
{"id":1366,"date":"2015-12-16T21:57:48","date_gmt":"2015-12-16T21:57:48","guid":{"rendered":"http:\/\/arlberg-guides.at\/eng\/wp-content\/uploads\/2015\/04\/image1.jpg"},"modified":"2015-12-16T21:57:48","modified_gmt":"2015-12-16T21:57:48","slug":"image1-2","status":"inherit","type":"attachment","link":"https:\/\/arlberg-guides.at\/eng\/team\/image1-2\/","title":{"rendered":"image1"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-1366","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/arlberg-guides.at\/eng\/wp-content\/uploads\/2015\/04\/image1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"229\" height=\"300\" src=\"https:\/\/arlberg-guides.at\/eng\/wp-content\/uploads\/2015\/04\/image1-229x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/arlberg-guides.at\/eng\/wp-content\/uploads\/2015\/04\/image1-229x300.jpg 229w, https:\/\/arlberg-guides.at\/eng\/wp-content\/uploads\/2015\/04\/image1.jpg 488w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":488,"height":640,"file":"2015\/04\/image1.jpg","sizes":{"thumbnail":{"file":"image1-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/arlberg-guides.at\/eng\/wp-content\/uploads\/2015\/04\/image1-150x150.jpg"},"medium":{"file":"image1-229x300.jpg","width":229,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/arlberg-guides.at\/eng\/wp-content\/uploads\/2015\/04\/image1-229x300.jpg"},"full":{"file":"image1.jpg","width":488,"height":640,"mime_type":"image\/jpeg","source_url":"https:\/\/arlberg-guides.at\/eng\/wp-content\/uploads\/2015\/04\/image1.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":170,"source_url":"https:\/\/arlberg-guides.at\/eng\/wp-content\/uploads\/2015\/04\/image1.jpg","_links":{"self":[{"href":"https:\/\/arlberg-guides.at\/eng\/wp-json\/wp\/v2\/media\/1366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arlberg-guides.at\/eng\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/arlberg-guides.at\/eng\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/arlberg-guides.at\/eng\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/arlberg-guides.at\/eng\/wp-json\/wp\/v2\/comments?post=1366"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":170,"href":"https:\/\/arlberg-guides.at\/eng\/wp-json\/wp\/v2\/pages\/170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}